{"id":3679,"date":"2013-04-30T09:38:33","date_gmt":"2013-04-30T08:38:33","guid":{"rendered":"https:\/\/mylondontradesmen.co.uk\/wp68\/?p=3679"},"modified":"2019-07-16T10:21:50","modified_gmt":"2019-07-16T09:21:50","slug":"gas-safety-certificate-in-se13-lewisham","status":"publish","type":"post","link":"https:\/\/mylondontradesmen.co.uk\/wp68\/blog\/gas-safety-certificate-in-se13-lewisham\/","title":{"rendered":"Gas Safety Certificate in SE13 Lewisham"},"content":{"rendered":"<p>Homeowners and landlords in the area of SE13 Lewisham, South East London, who are planning on renting out their properties, must make sure that they have a valid gas safety certificate for their properties before the tenants move in. The Gas Safety certificate in SE13 Lewisham, South East London, is about assessing the safety of the gas appliances in the property, so that a tenant can live in the property safely.<\/p>\n<p>Older appliances need to be maintained on a regular basis, otherwise they can be unexpectedly breakdown, which will evidently lead to a lot of money being spent to repair or replace the appliance. This is why we advise that you have a cooker or boiler service at least once a year, to avoid any unexpected breakdowns. Newer gas appliances can also be dangerous if they are not installed properly, so make sure that you get a <a title=\"Gas Safe Register\" href=\"http:\/\/www.gassaferegister.co.uk\/\">gas safe registered engineer<\/a> to install the gas appliance as they have the knowledge and skill to install the appliance safely.<\/p>\n<p>To learn more about the regulations that affect your gas cooker in SE13 Lewisham, South East London, or to book a quick and reliable gas appliance service, installation or an inspection for a gas safety certificate in SE13 Lewisham, South East London, please submit your desired job on My London Tradesmen and you will receive up to three quotes from three different companies most suited to your requirements.<\/p>\n<p>All the tradesmen that are suggested to you will all have up to date training and are able to do any kind of gas safety certificate in SE13 Lewisham, South East London as well as being registered to all the necessary bodies as well as being trustworthy. The process is simple in order to receive high quality gas appliance work at your home in SE13 Lewisham, South East London.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Homeowners and landlords in the area of SE13 Lewisham, South East London, who are planning on renting out their properties, must make sure that they have a valid gas safety certificate for their properties before the tenants move in. The Gas Safety certificate in SE13 Lewisham, South East London, is about assessing the safety of<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[62],"tags":[82,744,545],"class_list":["post-3679","post","type-post","status-publish","format-standard","hentry","category-safety-certificate","tag-gas-safety-certificate","tag-se13-lewisham","tag-south-east-london"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gas Safety Certificate in SE13 Lewisham | My London Tradesmen<\/title>\n<meta name=\"description\" content=\"Find out it is so important that you have a valid Gas Safety Certificate in SE13 Lewisham, before any tenant moves into the property, in terms of safety.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mylondontradesmen.co.uk\/wp68\/blog\/gas-safety-certificate-in-se13-lewisham\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gas Safety Certificate in SE13 Lewisham | My London Tradesmen\" \/>\n<meta property=\"og:description\" content=\"Find out it is so important that you have a valid Gas Safety Certificate in SE13 Lewisham, before any tenant moves into the property, in terms of safety.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mylondontradesmen.co.uk\/wp68\/blog\/gas-safety-certificate-in-se13-lewisham\/\" \/>\n<meta property=\"og:site_name\" content=\"My London Tradesmen\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-30T08:38:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-16T09:21:50+00:00\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/blog\\\/gas-safety-certificate-in-se13-lewisham\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/blog\\\/gas-safety-certificate-in-se13-lewisham\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/#\\\/schema\\\/person\\\/507404eb6632eba84da6f98a27cd2444\"},\"headline\":\"Gas Safety Certificate in SE13 Lewisham\",\"datePublished\":\"2013-04-30T08:38:33+00:00\",\"dateModified\":\"2019-07-16T09:21:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/blog\\\/gas-safety-certificate-in-se13-lewisham\\\/\"},\"wordCount\":311,\"publisher\":{\"@id\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/#organization\"},\"keywords\":[\"gas safety certificate\",\"SE13 Lewisham\",\"south east london\"],\"articleSection\":[\"Safety Certificate\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/blog\\\/gas-safety-certificate-in-se13-lewisham\\\/\",\"url\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/blog\\\/gas-safety-certificate-in-se13-lewisham\\\/\",\"name\":\"Gas Safety Certificate in SE13 Lewisham | My London Tradesmen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/#website\"},\"datePublished\":\"2013-04-30T08:38:33+00:00\",\"dateModified\":\"2019-07-16T09:21:50+00:00\",\"description\":\"Find out it is so important that you have a valid Gas Safety Certificate in SE13 Lewisham, before any tenant moves into the property, in terms of safety.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/blog\\\/gas-safety-certificate-in-se13-lewisham\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/blog\\\/gas-safety-certificate-in-se13-lewisham\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/blog\\\/gas-safety-certificate-in-se13-lewisham\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gas Safety Certificate in SE13 Lewisham\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/#website\",\"url\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/\",\"name\":\"My London Tradesmen\",\"description\":\"for trusted, local tradesmen\",\"publisher\":{\"@id\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/#organization\",\"name\":\"My London Tradesmen\",\"url\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/MyLondonTradesmen-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/MyLondonTradesmen-logo-1.png\",\"width\":250,\"height\":79,\"caption\":\"My London Tradesmen\"},\"image\":{\"@id\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/#\\\/schema\\\/person\\\/507404eb6632eba84da6f98a27cd2444\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90b1c0d2fb9f25d952e86198ffccb98d68d088661d6f6035a879403b69ec3567?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90b1c0d2fb9f25d952e86198ffccb98d68d088661d6f6035a879403b69ec3567?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90b1c0d2fb9f25d952e86198ffccb98d68d088661d6f6035a879403b69ec3567?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/mylondontradesmen.co.uk\\\/wp68\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gas Safety Certificate in SE13 Lewisham | My London Tradesmen","description":"Find out it is so important that you have a valid Gas Safety Certificate in SE13 Lewisham, before any tenant moves into the property, in terms of safety.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mylondontradesmen.co.uk\/wp68\/blog\/gas-safety-certificate-in-se13-lewisham\/","og_locale":"en_GB","og_type":"article","og_title":"Gas Safety Certificate in SE13 Lewisham | My London Tradesmen","og_description":"Find out it is so important that you have a valid Gas Safety Certificate in SE13 Lewisham, before any tenant moves into the property, in terms of safety.","og_url":"https:\/\/mylondontradesmen.co.uk\/wp68\/blog\/gas-safety-certificate-in-se13-lewisham\/","og_site_name":"My London Tradesmen","article_published_time":"2013-04-30T08:38:33+00:00","article_modified_time":"2019-07-16T09:21:50+00:00","author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mylondontradesmen.co.uk\/wp68\/blog\/gas-safety-certificate-in-se13-lewisham\/#article","isPartOf":{"@id":"https:\/\/mylondontradesmen.co.uk\/wp68\/blog\/gas-safety-certificate-in-se13-lewisham\/"},"author":{"name":"Admin","@id":"https:\/\/mylondontradesmen.co.uk\/wp68\/#\/schema\/person\/507404eb6632eba84da6f98a27cd2444"},"headline":"Gas Safety Certificate in SE13 Lewisham","datePublished":"2013-04-30T08:38:33+00:00","dateModified":"2019-07-16T09:21:50+00:00","mainEntityOfPage":{"@id":"https:\/\/mylondontradesmen.co.uk\/wp68\/blog\/gas-safety-certificate-in-se13-lewisham\/"},"wordCount":311,"publisher":{"@id":"https:\/\/mylondontradesmen.co.uk\/wp68\/#organization"},"keywords":["gas safety certificate","SE13 Lewisham","south east london"],"articleSection":["Safety Certificate"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/mylondontradesmen.co.uk\/wp68\/blog\/gas-safety-certificate-in-se13-lewisham\/","url":"https:\/\/mylondontradesmen.co.uk\/wp68\/blog\/gas-safety-certificate-in-se13-lewisham\/","name":"Gas Safety Certificate in SE13 Lewisham | My London Tradesmen","isPartOf":{"@id":"https:\/\/mylondontradesmen.co.uk\/wp68\/#website"},"datePublished":"2013-04-30T08:38:33+00:00","dateModified":"2019-07-16T09:21:50+00:00","description":"Find out it is so important that you have a valid Gas Safety Certificate in SE13 Lewisham, before any tenant moves into the property, in terms of safety.","breadcrumb":{"@id":"https:\/\/mylondontradesmen.co.uk\/wp68\/blog\/gas-safety-certificate-in-se13-lewisham\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mylondontradesmen.co.uk\/wp68\/blog\/gas-safety-certificate-in-se13-lewisham\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mylondontradesmen.co.uk\/wp68\/blog\/gas-safety-certificate-in-se13-lewisham\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mylondontradesmen.co.uk\/wp68\/"},{"@type":"ListItem","position":2,"name":"Gas Safety Certificate in SE13 Lewisham"}]},{"@type":"WebSite","@id":"https:\/\/mylondontradesmen.co.uk\/wp68\/#website","url":"https:\/\/mylondontradesmen.co.uk\/wp68\/","name":"My London Tradesmen","description":"for trusted, local tradesmen","publisher":{"@id":"https:\/\/mylondontradesmen.co.uk\/wp68\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mylondontradesmen.co.uk\/wp68\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/mylondontradesmen.co.uk\/wp68\/#organization","name":"My London Tradesmen","url":"https:\/\/mylondontradesmen.co.uk\/wp68\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/mylondontradesmen.co.uk\/wp68\/#\/schema\/logo\/image\/","url":"https:\/\/mylondontradesmen.co.uk\/wp68\/wp-content\/uploads\/2019\/03\/MyLondonTradesmen-logo-1.png","contentUrl":"https:\/\/mylondontradesmen.co.uk\/wp68\/wp-content\/uploads\/2019\/03\/MyLondonTradesmen-logo-1.png","width":250,"height":79,"caption":"My London Tradesmen"},"image":{"@id":"https:\/\/mylondontradesmen.co.uk\/wp68\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mylondontradesmen.co.uk\/wp68\/#\/schema\/person\/507404eb6632eba84da6f98a27cd2444","name":"Admin","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/90b1c0d2fb9f25d952e86198ffccb98d68d088661d6f6035a879403b69ec3567?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/90b1c0d2fb9f25d952e86198ffccb98d68d088661d6f6035a879403b69ec3567?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90b1c0d2fb9f25d952e86198ffccb98d68d088661d6f6035a879403b69ec3567?s=96&d=mm&r=g","caption":"Admin"},"url":"https:\/\/mylondontradesmen.co.uk\/wp68\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/mylondontradesmen.co.uk\/wp68\/wp-json\/wp\/v2\/posts\/3679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mylondontradesmen.co.uk\/wp68\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mylondontradesmen.co.uk\/wp68\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mylondontradesmen.co.uk\/wp68\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mylondontradesmen.co.uk\/wp68\/wp-json\/wp\/v2\/comments?post=3679"}],"version-history":[{"count":0,"href":"https:\/\/mylondontradesmen.co.uk\/wp68\/wp-json\/wp\/v2\/posts\/3679\/revisions"}],"wp:attachment":[{"href":"https:\/\/mylondontradesmen.co.uk\/wp68\/wp-json\/wp\/v2\/media?parent=3679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mylondontradesmen.co.uk\/wp68\/wp-json\/wp\/v2\/categories?post=3679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mylondontradesmen.co.uk\/wp68\/wp-json\/wp\/v2\/tags?post=3679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}